{"id":6087,"date":"2018-09-24T10:07:28","date_gmt":"2018-09-24T06:07:28","guid":{"rendered":"http:\/\/wpetab.ac-reunion.fr\/jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site.jpg"},"modified":"2018-09-24T10:07:28","modified_gmt":"2018-09-24T06:07:28","slug":"competition-4-maisons-logo-site","status":"inherit","type":"attachment","link":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/page-daccueil\/competition-4-maisons-logo-site\/","title":{"rendered":"competition 4 maisons logo site"},"author":13197,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6087","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"234\" src=\"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-300x234.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-300x234.jpg 300w, https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-150x117.jpg 150w, https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site.jpg 490w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/page-daccueil\/competition-4-maisons-logo-site\/\">Lire la suite<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":490,"height":383,"file":"2018\/09\/competition-4-maisons-logo-site.jpg","sizes":{"thumbnail":{"file":"competition-4-maisons-logo-site-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-150x150.jpg"},"medium":{"file":"competition-4-maisons-logo-site-300x234.jpg","width":300,"height":234,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-300x234.jpg"},"custom":{"file":"competition-4-maisons-logo-site-250x150.jpg","width":250,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-250x150.jpg"},"post-thumbnail":{"file":"competition-4-maisons-logo-site-150x117.jpg","width":150,"height":117,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-150x117.jpg"},"header":{"file":"competition-4-maisons-logo-site-490x120.jpg","width":490,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-490x120.jpg"},"columns":{"file":"competition-4-maisons-logo-site-490x201.jpg","width":490,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site-490x201.jpg"},"full":{"file":"competition-4-maisons-logo-site.jpg","width":490,"height":383,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":796,"source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/09\/competition-4-maisons-logo-site.jpg","_links":{"self":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/media\/6087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/users\/13197"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":796,"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/pages\/796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}