{"id":6761,"date":"2018-11-14T10:25:28","date_gmt":"2018-11-14T06:25:28","guid":{"rendered":"http:\/\/wpetab.ac-reunion.fr\/jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7.jpg"},"modified":"2018-11-14T10:25:28","modified_gmt":"2018-11-14T06:25:28","slug":"phil7-2","status":"inherit","type":"attachment","link":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/page-daccueil\/phil7-2\/","title":{"rendered":"phil7"},"author":13197,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6761","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-169x300.jpg 169w, https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-576x1024.jpg 576w, https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-84x150.jpg 84w, https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7.jpg 581w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/page-daccueil\/phil7-2\/\">Lire la suite<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":581,"height":1032,"file":"2018\/11\/phil7.jpg","sizes":{"thumbnail":{"file":"phil7-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-150x150.jpg"},"medium":{"file":"phil7-169x300.jpg","width":169,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-169x300.jpg"},"large":{"file":"phil7-576x1024.jpg","width":576,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-576x1024.jpg"},"custom":{"file":"phil7-250x150.jpg","width":250,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-250x150.jpg"},"post-thumbnail":{"file":"phil7-84x150.jpg","width":84,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-84x150.jpg"},"header":{"file":"phil7-581x120.jpg","width":581,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-581x120.jpg"},"slider":{"file":"phil7-581x400.jpg","width":581,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-581x400.jpg"},"columns":{"file":"phil7-549x201.jpg","width":549,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7-549x201.jpg"},"full":{"file":"phil7.jpg","width":581,"height":1032,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":796,"source_url":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-content\/uploads\/sites\/151\/2018\/11\/phil7.jpg","_links":{"self":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/media\/6761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/users\/13197"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":796,"href":"https:\/\/etab.ac-reunion.fr\/clg-jules-solesse\/wp-json\/wp\/v2\/pages\/796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}