{"id":1949,"date":"2015-03-26T09:43:19","date_gmt":"2015-03-26T05:43:19","guid":{"rendered":"http:\/\/wpetab.ac-reunion.fr\/les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015.jpg"},"modified":"2015-03-26T09:44:05","modified_gmt":"2015-03-26T05:44:05","slug":"hand2015","status":"inherit","type":"attachment","link":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/hand2015\/","title":{"rendered":"Hand2015"},"author":66,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-1949","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"Minimes m\u00e9daille\u00e9s de bronze - District nord 2015\" srcset=\"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-300x214.jpg 300w, https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015.jpg 964w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/hand2015\/\"><span>Lire la suite<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n"},"alt_text":"Minimes m\u00e9daille\u00e9s de bronze - District nord 2015","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":964,"height":689,"file":"2015\/03\/Hand2015.jpg","sizes":{"thumbnail":{"file":"Hand2015-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-150x150.jpg"},"medium":{"file":"Hand2015-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-300x214.jpg"},"et-blog-thumb":{"file":"Hand2015-630x210.jpg","width":630,"height":210,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-630x210.jpg"},"et-featured-thumb":{"file":"Hand2015-960x360.jpg","width":960,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-960x360.jpg"},"et-widget-fromblog-thumb":{"file":"Hand2015-37x37.jpg","width":37,"height":37,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-37x37.jpg"},"et-video-slider-thumb":{"file":"Hand2015-136x77.jpg","width":136,"height":77,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-136x77.jpg"},"et-home-image-thumb":{"file":"Hand2015-128x128.jpg","width":128,"height":128,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-128x128.jpg"},"et-blog-page-thumb":{"file":"Hand2015-184x184.jpg","width":184,"height":184,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-184x184.jpg"},"et-gallery-page-thumb":{"file":"Hand2015-207x136.jpg","width":207,"height":136,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-207x136.jpg"},"et-portfolio-medium-page-thumb":{"file":"Hand2015-260x170.jpg","width":260,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-260x170.jpg"},"et-portfolio-medium-portrait-page-thumb":{"file":"Hand2015-260x315.jpg","width":260,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-260x315.jpg"},"et-portfolio-small-page-thumb":{"file":"Hand2015-140x94.jpg","width":140,"height":94,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-140x94.jpg"},"et-portfolio-small-portrait-page-thumb":{"file":"Hand2015-140x170.jpg","width":140,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-140x170.jpg"},"et-portfolio-large-page-thumb":{"file":"Hand2015-430x283.jpg","width":430,"height":283,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-430x283.jpg"},"et-portfolio-large-portrait-page-thumb":{"file":"Hand2015-430x689.jpg","width":430,"height":689,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015-430x689.jpg"},"full":{"file":"Hand2015.jpg","width":964,"height":689,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":1}},"post":null,"source_url":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-content\/uploads\/sites\/21\/2015\/03\/Hand2015.jpg","_links":{"self":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-json\/wp\/v2\/media\/1949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/etab.ac-reunion.fr\/clg-les-mascareignes\/wp-json\/wp\/v2\/users\/66"}]}}