{"id":1701,"date":"2016-02-18T10:45:05","date_gmt":"2016-02-18T06:45:05","guid":{"rendered":"http:\/\/wpetab.ac-reunion.fr\/verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter.png"},"modified":"2016-02-18T10:45:05","modified_gmt":"2016-02-18T06:45:05","slug":"twitter","status":"inherit","type":"attachment","link":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/twitter\/","title":{"rendered":"twitter"},"author":157,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"class_list":["post-1701","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter.png'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"76\" src=\"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->"},"caption":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":272,"height":76,"file":"2016\/02\/twitter.png","sizes":{"thumbnail":{"file":"twitter-150x76.png","width":150,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-150x76.png"},"et-page-thumb":{"file":"twitter-200x76.png","width":200,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-200x76.png"},"et-entry-large-thumb":{"file":"twitter-130x76.png","width":130,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-130x76.png"},"et-widget-photostream-thumb":{"file":"twitter-67x67.png","width":67,"height":67,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-67x67.png"},"et-featured-slider-small-thumb":{"file":"twitter-95x54.png","width":95,"height":54,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-95x54.png"},"et-widget-fromblog-thumb":{"file":"twitter-40x40.png","width":40,"height":40,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-40x40.png"},"et-widget-recentvideos-thumb":{"file":"twitter-248x76.png","width":248,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-248x76.png"},"et-blog-page-thumb":{"file":"twitter-184x76.png","width":184,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-184x76.png"},"et-gallery-page-thumb":{"file":"twitter-207x76.png","width":207,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-207x76.png"},"et-portfolio-medium-page-thumb":{"file":"twitter-260x76.png","width":260,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-260x76.png"},"et-portfolio-medium-portrait-page-thumb":{"file":"twitter-260x76.png","width":260,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-260x76.png"},"et-portfolio-small-page-thumb":{"file":"twitter-140x76.png","width":140,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-140x76.png"},"et-portfolio-small-portrait-page-thumb":{"file":"twitter-140x76.png","width":140,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter-140x76.png"},"full":{"file":"twitter.png","width":272,"height":76,"mime_type":"image\/png","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-content\/uploads\/sites\/32\/2016\/02\/twitter.png","_links":{"self":[{"href":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-json\/wp\/v2\/media\/1701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/etab.ac-reunion.fr\/lyc-le-verger\/wp-json\/wp\/v2\/users\/157"}]}}