{"id":1669,"date":"2015-05-16T17:32:08","date_gmt":"2015-05-16T13:32:08","guid":{"rendered":"http:\/\/wpetab.ac-reunion.fr\/victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6.jpg"},"modified":"2015-05-16T17:32:08","modified_gmt":"2015-05-16T13:32:08","slug":"biblio6","status":"inherit","type":"attachment","link":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/biblio6\/","title":{"rendered":"biblio6"},"author":2226,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-1669","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"230\" src=\"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-300x230.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-300x230.jpg 300w, https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-1024x784.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/biblio6\/\"><span>Lire le contenu<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3387,"height":2592,"file":"2015\/05\/biblio6.jpg","sizes":{"thumbnail":{"file":"biblio6-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-150x150.jpg"},"medium":{"file":"biblio6-300x230.jpg","width":300,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-300x230.jpg"},"large":{"file":"biblio6-1024x784.jpg","width":1024,"height":784,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-1024x784.jpg"},"et-usual-thumb":{"file":"biblio6-130x130.jpg","width":130,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-130x130.jpg"},"et-pages-thumb":{"file":"biblio6-140x140.jpg","width":140,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-140x140.jpg"},"et-featured-thumb":{"file":"biblio6-1400x300.jpg","width":1400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-1400x300.jpg"},"et-recent-cat-thumb":{"file":"biblio6-239x133.jpg","width":239,"height":133,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-239x133.jpg"},"et-custom-post-thumb":{"file":"biblio6-74x74.jpg","width":74,"height":74,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-74x74.jpg"},"et-blog-page-thumb":{"file":"biblio6-184x184.jpg","width":184,"height":184,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-184x184.jpg"},"et-gallery-page-thumb":{"file":"biblio6-207x136.jpg","width":207,"height":136,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-207x136.jpg"},"et-portfolio-medium-page-thumb":{"file":"biblio6-260x170.jpg","width":260,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-260x170.jpg"},"et-portfolio-medium-portrait-page-thumb":{"file":"biblio6-260x315.jpg","width":260,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-260x315.jpg"},"et-portfolio-small-page-thumb":{"file":"biblio6-140x94.jpg","width":140,"height":94,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-140x94.jpg"},"et-portfolio-small-portrait-page-thumb":{"file":"biblio6-140x170.jpg","width":140,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-140x170.jpg"},"et-portfolio-large-page-thumb":{"file":"biblio6-430x283.jpg","width":430,"height":283,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-430x283.jpg"},"et-portfolio-large-portrait-page-thumb":{"file":"biblio6-430x860.jpg","width":430,"height":860,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6-430x860.jpg"},"full":{"file":"biblio6.jpg","width":3387,"height":2592,"mime_type":"image\/jpeg","source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6.jpg"}},"image_meta":{"aperture":3.8,"credit":"","camera":"NIKON D60","caption":"","created_timestamp":1430733584,"copyright":"Wilfrid DIJOUX","focal_length":"20","iso":"200","shutter_speed":"0.033333333333333","title":"","orientation":0}},"post":null,"source_url":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-content\/uploads\/sites\/93\/2015\/05\/biblio6.jpg","_links":{"self":[{"href":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-json\/wp\/v2\/media\/1669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/etab.ac-reunion.fr\/lyc-victor-schoelcher\/wp-json\/wp\/v2\/users\/2226"}]}}